{"id":4086,"date":"2025-05-31T14:50:24","date_gmt":"2025-05-31T12:50:24","guid":{"rendered":"https:\/\/alaia.ch\/bay\/?p=4086"},"modified":"2026-03-17T18:27:05","modified_gmt":"2026-03-17T17:27:05","slug":"4086","status":"publish","type":"post","link":"https:\/\/alaia.ch\/bay\/4086\/","title":{"rendered":"Le r\u00f4le de la concentration et de l&rsquo;\u00e9tat de sprit dans le surf"},"content":{"rendered":"<p>En 2025, la sant\u00e9 mentale n\u2019est plus un sujet secondaire. Elle est au c\u0153ur de tout ce que nous faisons. Ces derni\u00e8res ann\u00e9es, de nombreux athl\u00e8tes de haut niveau ont d\u00e9cid\u00e9 de faire une pause \u2014 non pas \u00e0 cause d\u2019une blessure ou d\u2019une baisse de forme \u2014 mais pour prendre soin de leur esprit.<\/p>\n<p>Mais cette discussion d\u00e9passe largement le cadre de la WSL ou des comp\u00e9titions. Que vous surfiez pour monter sur un podium ou simplement pour le plaisir de glisser, votre esprit vous accompagne toujours dans la vague.<\/p>\n<p>Le surf n\u2019est pas un sport comme les autres. Il s\u2019agit de danser avec une force de la nature impr\u00e9visible, o\u00f9 vous n\u2019\u00eates que rarement en contr\u00f4le. C\u2019est l\u00e0 que l\u2019\u00e9tat d\u2019esprit entre en jeu. Bien plus que le physique ou l\u2019\u00e9quipement, c\u2019est la concentration mentale qui vous maintient \u00e0 flot quand l\u2019oc\u00e9an essaie de vous submerger.<\/p>\n<h3>SANT\u00c9 MENTALE : UNE VAGUE QUI MONTE DANS LA CULTURE SURF<\/h3>\n<p>Pendant des d\u00e9cennies, le surf a v\u00e9hicul\u00e9 une image de libert\u00e9, de \u201claisser-aller\u201d. Mais derri\u00e8re cette attitude d\u00e9tendue, nombreux sont les surfeurs \u2014 pros ou amateurs \u2014 qui ont lutt\u00e9 en silence avec la pression, le burn-out, la peur ou la frustration.<\/p>\n<p>Aujourd\u2019hui, les choses \u00e9voluent. Le sport se structure, devient plus comp\u00e9titif, et surtout, plus transparent sur ce qu\u2019il faut vraiment pour durer.<\/p>\n<p>L\u2019ancien surfeur du Championship Tour, Tiago Pires, le sait mieux que quiconque. Apr\u00e8s plus de dix ans sur le circuit mondial, il a vu le surf \u00e9voluer, et avec lui, l\u2019importance de l\u2019aspect mental.<\/p>\n<p>\u00ab Le surf devient bien plus comp\u00e9titif, notamment avec les Jeux Olympiques. Des athl\u00e8tes issus d\u2019autres sports arrivent avec leur exp\u00e9rience. C\u2019est pour \u00e7a que l\u2019aspect mental prend autant d\u2019importance. Les grands r\u00e9sultats viennent souvent de la r\u00e9silience mentale, de la strat\u00e9gie, et de la capacit\u00e9 \u00e0 g\u00e9rer la pression. \u00bb<\/p>\n<p>Mais il ne s\u2019agit pas uniquement de victoires. Pour Tiago, la sant\u00e9 mentale est aussi une question de long\u00e9vit\u00e9.<\/p>\n<p>\u00ab On ne reste pas plus de dix ans au plus haut niveau sans prendre soin de sa t\u00eate. Il faut de l\u2019\u00e9quilibre pour encaisser la pression d\u2019une saison compl\u00e8te et plus encore. \u00bb<\/p>\n<h3>L\u2019\u00c9TAT D\u2019ESPRIT EN COMP\u00c9TITION : TIAGO PIRES ET LA FORCE MENTALE<\/h3>\n<p>Sur l\u2019aspect mental du surf, Tiago est clair :<\/p>\n<p>\u00ab Le surf, c\u2019est 70 % mental, 30 % technique. \u00bb<\/p>\n<p>Il admet que, plus jeune, il se concentrait surtout sur la performance technique. Mais il sentait qu\u2019il manquait quelque chose.<\/p>\n<p>\u00ab Jusqu\u2019\u00e0 mes 25 ans, je progressais beaucoup techniquement. J\u2019ai eu de bons r\u00e9sultats. Mais je n\u2019atteignais pas le niveau auquel je voulais \u00eatre. \u00c7a n\u2019est venu qu\u2019apr\u00e8s un vrai travail mental. \u00bb<\/p>\n<p>Ce qui a tout chang\u00e9 ? La pr\u00e9paration mentale. La clart\u00e9. La capacit\u00e9 \u00e0 rester calme quand tout autour devient chaotique.<\/p>\n<p>\u00ab La p\u00e9riode avant une comp\u00e9tition est essentielle. Il faut y entrer positivement, avec confiance, pr\u00eat \u00e0 faire face. Parce qu\u2019il y aura des surprises : conditions compliqu\u00e9es, d\u00e9cisions injustes\u2026 Ceux qui restent calmes sous pression, ce sont ceux-l\u00e0 qui gagnent. \u00bb<\/p>\n<p>Le talent vous met peut-\u00eatre dans le maillot. Mais c\u2019est votre mental qui vous am\u00e8ne jusqu\u2019\u00e0 la derni\u00e8re vague.<\/p>\n<h3>SURFER POUR LE PLAISIR : LE COMBAT INT\u00c9RIEUR DU QUOTIDIEN<\/h3>\n<p>Pas besoin de viser les m\u00e9dailles pour ressentir le d\u00e9fi mental du surf. Chaque session vous teste : vagues d\u00e9sordonn\u00e9es, fatigue physique, doutes persistants\u2026 M\u00eame \u00e0 Ala\u00efa Bay, o\u00f9 les vagues sont pr\u00e9visibles, l\u2019\u00e9tat d\u2019esprit, lui, ne l\u2019est pas toujours.<\/p>\n<p>Tiago insiste : ce travail mental n\u2019est pas r\u00e9serv\u00e9 aux pros.<\/p>\n<p>\u00ab Le temps pass\u00e9 dans l\u2019eau est le meilleur professeur. Plus on passe d\u2019heures l\u00e0, plus on apprend \u00e0 g\u00e9rer ses peurs et \u00e0 gagner en confiance. \u00bb<\/p>\n<p>Mais il encourage aussi les surfeurs interm\u00e9diaires \u00e0 aller plus loin.<\/p>\n<p>\u00ab L\u2019apn\u00e9e, le travail respiratoire, \u00e7a renforce la confiance. Le yoga et la m\u00e9ditation, \u00e7a aide \u00e0 ralentir quand la panique veut prendre le dessus. \u00bb<\/p>\n<p>Il explique que dans les situations de stress, c\u2019est l\u2019esprit calme qui permet de garder son souffle et ses r\u00e9flexes.<\/p>\n<p>\u00ab Quand tu stresses, ta respiration devient courte. Tu perds le contr\u00f4le. Mais si tu as appris \u00e0 rester calme, tu tiens plus longtemps sous l\u2019eau. Tu traverses mieux les situations difficiles. \u00bb<\/p>\n<figure id=\"attachment_4072\" aria-describedby=\"caption-attachment-4072\" style=\"width: 1176px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4072\" src=\"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-26-at-16.27.20.jpeg\" alt=\"\" width=\"1176\" height=\"794\" srcset=\"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-26-at-16.27.20.jpeg 1080w, https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-26-at-16.27.20-300x203.jpeg 300w, https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-26-at-16.27.20-1024x691.jpeg 1024w, https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-26-at-16.27.20-768x518.jpeg 768w\" sizes=\"auto, (max-width: 1176px) 100vw, 1176px\" \/><figcaption id=\"caption-attachment-4072\" class=\"wp-caption-text\">Tiago \u00ab\u00a0Saca\u00a0\u00bb Pires surfing Tahiti for the soul.<\/figcaption><\/figure>\n<h3>LE SURF ENSEIGNE LE L\u00c2CHER-PRISE<\/h3>\n<p>Le surf est une le\u00e7on d\u2019humilit\u00e9. Il vous montre vos limites \u2014 puis les repousse, doucement ou brutalement.<\/p>\n<p>On ne peut pas forcer l\u2019oc\u00e9an. On ne peut pas pr\u00e9voir chaque s\u00e9rie. Mais on peut arriver dans l\u2019eau avec de la concentration, de la flexibilit\u00e9, et la capacit\u00e9 \u00e0 recommencer, encore et encore.<\/p>\n<p>L\u00e0-bas, vous n\u2019avez pas le contr\u00f4le. Mais votre souffle, oui. Votre attention, oui.<\/p>\n<p>C\u2019est ce qui rend le surf si diff\u00e9rent d\u2019un entra\u00eenement en salle ou d\u2019un sport collectif. Ce n\u2019est pas juste physique, c\u2019est intime. Et c\u2019est pour \u00e7a que l\u2019\u00e9tat d\u2019esprit est essentiel, que vous soyez dans une wavepool ou sur un reef \u00e0 l\u2019autre bout du monde.<\/p>\n<h3>OUTILS MENTAUX POUR SURFEURS : CONSTRUIRE UN ESPRIT PLUS FORT<\/h3>\n<p>Tiago nous partage quelques conseils concrets, des outils que tout surfeur peut int\u00e9grer :<\/p>\n<p>\u2022Visualisation avant session ou comp\u00e9tition : Anticiper les impr\u00e9vus, penser aux solutions, arriver avec un plan.<\/p>\n<p>\u2022Travail respiratoire : Apn\u00e9e, exercices de respiration sp\u00e9cifiques au surf, pour rester calme lors des wipeouts.<\/p>\n<p>\u2022Pratiques de pleine conscience : M\u00e9ditation, yoga, journaling, ou simplement un moment de calme apr\u00e8s la session.<\/p>\n<p>\u2022Coaching mental : Travailler avec des coachs ou des psychologues du sport devient de plus en plus courant, m\u00eame hors circuit pro.<\/p>\n<p>\u2022Et surtout : la r\u00e9gularit\u00e9. La sant\u00e9 mentale se travaille comme la condition physique. Plus on pratique, plus \u00e7a devient naturel.<\/p>\n<h3>SURFER LES HAUTS, ACCEPTER LES BAS<\/h3>\n<p>Le surf vous mettra \u00e0 l\u2019\u00e9preuve. Pas seulement votre technique, mais aussi votre capacit\u00e9 \u00e0 garder le cap quand la mar\u00e9e change \u2014 mentalement et \u00e9motionnellement.<\/p>\n<p>Que vous partiez sur votre premi\u00e8re vague ou que vous luttiez dans un heat, c\u2019est le mental qui fera la diff\u00e9rence. C\u2019est lui qui vous pousse \u00e0 ramer alors que vos bras n\u2019en peuvent plus. Qui vous aide \u00e0 dig\u00e9rer une mauvaise vague. Qui vous dit que c\u2019est ok de recommencer.<\/p>\n<p>Alors, la prochaine fois que vous waxez votre planche, prenez une minute pour faire un check mental aussi.<\/p>\n<h3>BESOIN DE VOUS RECONNECTER ? VENEZ \u00c0 ALA\u00cfA BAY<\/h3>\n<p>Que vous travailliez votre backside, repreniez confiance apr\u00e8s un wipeout, ou cherchiez simplement cet \u00e9tat de flow, Ala\u00efa Bay est votre terrain de reconnexion. Des vagues r\u00e9guli\u00e8res, une bonne ambiance, et une \u00e9quipe qui comprend.<\/p>\n<p>Venez comme vous \u00eates. Le reste ? On le surfe ensemble.<\/p>\n<p>R\u00e9servez votre prochaine session ou \u00e9changez avec l\u2019un de nos coachs sur l\u2019aspect mental de votre surf. Dans ce line-up, vous n\u2019\u00eates pas seul.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2025, la sant\u00e9 mentale n\u2019est plus un sujet secondaire. Elle est au c\u0153ur de tout ce que nous faisons. Ces derni\u00e8res ann\u00e9es, de nombreux athl\u00e8tes de haut niveau ont d\u00e9cid\u00e9 de faire une pause \u2014 non pas \u00e0 cause d\u2019une blessure ou d\u2019une baisse de forme \u2014 mais pour prendre soin de leur esprit.<\/p>\n","protected":false},"author":8,"featured_media":4111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le r\u00f4le de la concentration et de l&#039;\u00e9tat de sprit dans le surf - Ala\u00efa Bay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alaia.ch\/bay\/4086\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le r\u00f4le de la concentration et de l&#039;\u00e9tat de sprit dans le surf - Ala\u00efa Bay\" \/>\n<meta property=\"og:description\" content=\"En 2025, la sant\u00e9 mentale n\u2019est plus un sujet secondaire. Elle est au c\u0153ur de tout ce que nous faisons. Ces derni\u00e8res ann\u00e9es, de nombreux athl\u00e8tes de haut niveau ont d\u00e9cid\u00e9 de faire une pause \u2014 non pas \u00e0 cause d\u2019une blessure ou d\u2019une baisse de forme \u2014 mais pour prendre soin de leur esprit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alaia.ch\/bay\/4086\/\" \/>\n<meta property=\"og:site_name\" content=\"Ala\u00efa Bay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/alaia.bay\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-31T12:50:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T17:27:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-26-at-16.24.15.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1087\" \/>\n\t<meta property=\"og:image:height\" content=\"723\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel Tamaki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Tamaki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/4086\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/4086\\\/\"},\"author\":{\"name\":\"Gabriel Tamaki\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#\\\/schema\\\/person\\\/ea1f05705b83f9b2b98d213ee4a71f4e\"},\"headline\":\"Le r\u00f4le de la concentration et de l&rsquo;\u00e9tat de sprit dans le surf\",\"datePublished\":\"2025-05-31T12:50:24+00:00\",\"dateModified\":\"2026-03-17T17:27:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/4086\\\/\"},\"wordCount\":1233,\"publisher\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/4086\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-26-at-16.24.15.jpeg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/4086\\\/\",\"url\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/4086\\\/\",\"name\":\"Le r\u00f4le de la concentration et de l'\u00e9tat de sprit dans le surf - Ala\u00efa Bay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/4086\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/4086\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-26-at-16.24.15.jpeg\",\"datePublished\":\"2025-05-31T12:50:24+00:00\",\"dateModified\":\"2026-03-17T17:27:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/4086\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alaia.ch\\\/bay\\\/4086\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/4086\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-26-at-16.24.15.jpeg\",\"contentUrl\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/WhatsApp-Image-2025-05-26-at-16.24.15.jpeg\",\"width\":1087,\"height\":723},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/4086\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le r\u00f4le de la concentration et de l&#8217;\u00e9tat de sprit dans le surf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#website\",\"url\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/\",\"name\":\"Ala\u00efa Bay\",\"description\":\"Surf the Swiss Alps!\",\"publisher\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#organization\",\"name\":\"Ala\u00efa Bay\",\"url\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-alaia-bay.png\",\"contentUrl\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-alaia-bay.png\",\"width\":160,\"height\":160,\"caption\":\"Ala\u00efa Bay\"},\"image\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/alaia.bay\\\/\",\"https:\\\/\\\/www.instagram.com\\\/alaia.bay\\\/?hl=en\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/AlaaActionSports\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/alaa-sa\",\"https:\\\/\\\/www.tiktok.com\\\/@alaia.actionsports\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#\\\/schema\\\/person\\\/ea1f05705b83f9b2b98d213ee4a71f4e\",\"name\":\"Gabriel Tamaki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/527c525ca810298742b7d6aea0f4060139600bed2924aa5ad6c84b3068f0d6f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/527c525ca810298742b7d6aea0f4060139600bed2924aa5ad6c84b3068f0d6f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/527c525ca810298742b7d6aea0f4060139600bed2924aa5ad6c84b3068f0d6f7?s=96&d=mm&r=g\",\"caption\":\"Gabriel Tamaki\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le r\u00f4le de la concentration et de l'\u00e9tat de sprit dans le surf - Ala\u00efa Bay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alaia.ch\/bay\/4086\/","og_locale":"fr_FR","og_type":"article","og_title":"Le r\u00f4le de la concentration et de l'\u00e9tat de sprit dans le surf - Ala\u00efa Bay","og_description":"En 2025, la sant\u00e9 mentale n\u2019est plus un sujet secondaire. Elle est au c\u0153ur de tout ce que nous faisons. Ces derni\u00e8res ann\u00e9es, de nombreux athl\u00e8tes de haut niveau ont d\u00e9cid\u00e9 de faire une pause \u2014 non pas \u00e0 cause d\u2019une blessure ou d\u2019une baisse de forme \u2014 mais pour prendre soin de leur esprit.","og_url":"https:\/\/alaia.ch\/bay\/4086\/","og_site_name":"Ala\u00efa Bay","article_publisher":"https:\/\/www.facebook.com\/alaia.bay\/","article_published_time":"2025-05-31T12:50:24+00:00","article_modified_time":"2026-03-17T17:27:05+00:00","og_image":[{"width":1087,"height":723,"url":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-26-at-16.24.15.jpeg","type":"image\/jpeg"}],"author":"Gabriel Tamaki","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gabriel Tamaki","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alaia.ch\/bay\/4086\/#article","isPartOf":{"@id":"https:\/\/alaia.ch\/bay\/4086\/"},"author":{"name":"Gabriel Tamaki","@id":"https:\/\/alaia.ch\/bay\/#\/schema\/person\/ea1f05705b83f9b2b98d213ee4a71f4e"},"headline":"Le r\u00f4le de la concentration et de l&rsquo;\u00e9tat de sprit dans le surf","datePublished":"2025-05-31T12:50:24+00:00","dateModified":"2026-03-17T17:27:05+00:00","mainEntityOfPage":{"@id":"https:\/\/alaia.ch\/bay\/4086\/"},"wordCount":1233,"publisher":{"@id":"https:\/\/alaia.ch\/bay\/#organization"},"image":{"@id":"https:\/\/alaia.ch\/bay\/4086\/#primaryimage"},"thumbnailUrl":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-26-at-16.24.15.jpeg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/alaia.ch\/bay\/4086\/","url":"https:\/\/alaia.ch\/bay\/4086\/","name":"Le r\u00f4le de la concentration et de l'\u00e9tat de sprit dans le surf - Ala\u00efa Bay","isPartOf":{"@id":"https:\/\/alaia.ch\/bay\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alaia.ch\/bay\/4086\/#primaryimage"},"image":{"@id":"https:\/\/alaia.ch\/bay\/4086\/#primaryimage"},"thumbnailUrl":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-26-at-16.24.15.jpeg","datePublished":"2025-05-31T12:50:24+00:00","dateModified":"2026-03-17T17:27:05+00:00","breadcrumb":{"@id":"https:\/\/alaia.ch\/bay\/4086\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alaia.ch\/bay\/4086\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/alaia.ch\/bay\/4086\/#primaryimage","url":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-26-at-16.24.15.jpeg","contentUrl":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-26-at-16.24.15.jpeg","width":1087,"height":723},{"@type":"BreadcrumbList","@id":"https:\/\/alaia.ch\/bay\/4086\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alaia.ch\/bay\/"},{"@type":"ListItem","position":2,"name":"Le r\u00f4le de la concentration et de l&#8217;\u00e9tat de sprit dans le surf"}]},{"@type":"WebSite","@id":"https:\/\/alaia.ch\/bay\/#website","url":"https:\/\/alaia.ch\/bay\/","name":"Ala\u00efa Bay","description":"Surf the Swiss Alps!","publisher":{"@id":"https:\/\/alaia.ch\/bay\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alaia.ch\/bay\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/alaia.ch\/bay\/#organization","name":"Ala\u00efa Bay","url":"https:\/\/alaia.ch\/bay\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/alaia.ch\/bay\/#\/schema\/logo\/image\/","url":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/05\/logo-alaia-bay.png","contentUrl":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/05\/logo-alaia-bay.png","width":160,"height":160,"caption":"Ala\u00efa Bay"},"image":{"@id":"https:\/\/alaia.ch\/bay\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alaia.bay\/","https:\/\/www.instagram.com\/alaia.bay\/?hl=en","https:\/\/www.youtube.com\/c\/AlaaActionSports\/","https:\/\/www.linkedin.com\/company\/alaa-sa","https:\/\/www.tiktok.com\/@alaia.actionsports"]},{"@type":"Person","@id":"https:\/\/alaia.ch\/bay\/#\/schema\/person\/ea1f05705b83f9b2b98d213ee4a71f4e","name":"Gabriel Tamaki","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/527c525ca810298742b7d6aea0f4060139600bed2924aa5ad6c84b3068f0d6f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/527c525ca810298742b7d6aea0f4060139600bed2924aa5ad6c84b3068f0d6f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/527c525ca810298742b7d6aea0f4060139600bed2924aa5ad6c84b3068f0d6f7?s=96&d=mm&r=g","caption":"Gabriel Tamaki"}}]}},"_links":{"self":[{"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/posts\/4086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/comments?post=4086"}],"version-history":[{"count":8,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/posts\/4086\/revisions"}],"predecessor-version":[{"id":5545,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/posts\/4086\/revisions\/5545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/media\/4111"}],"wp:attachment":[{"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/media?parent=4086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/categories?post=4086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/tags?post=4086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}