{"id":2362,"date":"2024-04-02T09:32:39","date_gmt":"2024-04-02T07:32:39","guid":{"rendered":"https:\/\/alaiabay.ch\/?p=2362"},"modified":"2026-03-17T18:40:37","modified_gmt":"2026-03-17T17:40:37","slug":"les-piscines-a-vagues-sont-elles-la-solution","status":"publish","type":"post","link":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/","title":{"rendered":"Les mar\u00e9es noires du surf: les piscines \u00e0 vagues sont-elles la solution?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Le fait que le surf soit reconnu comme sport olympique est un tournant \u00e0 la fois doux et amer, un sentiment partag\u00e9 par de nombreux surfeurs. Les d\u00e9cisions controvers\u00e9es du comit\u00e9 olympique \u00e0 Teahupo\u02bbo, en Polyn\u00e9sie fran\u00e7aise, ont d\u00e9clench\u00e9 une friction croissante entre les \u00e9cologistes, les surfeurs et le monde du surf comp\u00e9titif. La d\u00e9cision de d\u00e9raciner des r\u00e9cifs coralliens anciens et intacts pour construire une tour de jugement pour les \u00e9v\u00e9nements de surf olympiques de 2024 est empreinte d&rsquo;une col\u00e8re et d&rsquo;un d\u00e9sarroi compr\u00e9hensibles. Cependant, cela a mis en lumi\u00e8re la question de savoir vraiment \u00e0 quel point le syst\u00e8me actuel de surf comp\u00e9titif est n\u00e9faste pour notre environnement. Les piscines \u00e0 vagues sont-elles la r\u00e9ponse dont le surf comp\u00e9titif a besoin?<\/span><\/p>\n<figure id=\"attachment_2305\" aria-describedby=\"caption-attachment-2305\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2305 size-full\" src=\"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/WSL-JUDGING-TOWER.jpg\" alt=\"La tour de jugement locale qui accueille le Tahiti Pro, et lepr\u00e9cieux r\u00e9cif en dessous. Photo : Tahiti Pro\/WSL. \" width=\"1024\" height=\"593\" srcset=\"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/WSL-JUDGING-TOWER.jpg 1024w, https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/WSL-JUDGING-TOWER-300x174.jpg 300w, https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/WSL-JUDGING-TOWER-768x445.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-2305\" class=\"wp-caption-text\">La tour de jugement locale qui accueille le Tahiti Pro, et le<br \/>pr\u00e9cieux r\u00e9cif en dessous. Photo : Tahiti Pro\/WSL.<\/figcaption><\/figure>\n<h4><span style=\"font-weight: 400;\">Alors, que se passe-t-il en Polyn\u00e9sie fran\u00e7aise?<\/span><\/h4>\n<p><span style=\"font-weight: 400;\"> La Polyn\u00e9sie fran\u00e7aise abrite l&rsquo;un des \u00e9cosyst\u00e8mes les plus diversifi\u00e9s au monde. Une oasis au milieu de l&rsquo;oc\u00e9an Pacifique sauvage, elle est souvent qualifi\u00e9e de lieu le plus prolifique de l&rsquo;\u00e9volution sur la plan\u00e8te. Les r\u00e9cifs coralliens qui bordent ces \u00eeles font partie des \u00e9cosyst\u00e8mes de r\u00e9cifs les plus intacts et les plus pr\u00e9serv\u00e9s au monde. Ils abritent des \u00e9cosyst\u00e8mes inexplor\u00e9s, certains d&rsquo;entre eux \u00e9tant d\u00e9couverts pour la premi\u00e8re fois aussi r\u00e9cemment qu&rsquo;en 2022. Ils ne sont pas rempla\u00e7ables, ayant besoin de mill\u00e9naires pour atteindre la maturit\u00e9 et la productivit\u00e9 de ceux qui sculptent les vagues \u00e0 Teahupo\u2019o. La sant\u00e9 de ces r\u00e9cifs a lentement d\u00e9clin\u00e9 depuis les ann\u00e9es 1970, un th\u00e8me observ\u00e9 \u00e0 travers le monde. Des fuites de produits p\u00e9trochimiques, du bruit des moteurs de bateaux en passant par les vagues de chaleur oc\u00e9aniques, c\u2019est ce que ces r\u00e9cifs ont d\u00fb tol\u00e9rer ces derni\u00e8res ann\u00e9es. Leur protection est au c\u0153ur du peuple polyn\u00e9sien.<\/span><\/p>\n<figure id=\"attachment_2308\" aria-describedby=\"caption-attachment-2308\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2308 size-large\" src=\"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1-1024x683.webp\" alt=\"Coraux \u00e0 Tahiti. Photo : Tahiti Tourisme (Gregory Lecoeur)\" width=\"750\" height=\"500\" srcset=\"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1-1024x683.webp 1024w, https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1-300x200.webp 300w, https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1-768x512.webp 768w, https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1.webp 1536w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-2308\" class=\"wp-caption-text\">Coraux \u00e0 Tahiti. Photo : Tahiti Tourisme (Gregory Lecoeur)<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Fondamentalement, sans r\u00e9cifs coralliens sains et intacts \u00e0 Teahupo\u2019o, il n&rsquo;y aurait pas de vagues. Ainsi, cela a \u00e9t\u00e9 un choc pour le syst\u00e8me lorsque les organisateurs olympiques ont propos\u00e9 de remplacer la tour en bois actuelle utilis\u00e9e pour juger les comp\u00e9titions \u00e0 Teahupo\u2019o jusqu&rsquo;en 2023, par une nouvelle tour en aluminium int\u00e9gr\u00e9e. La F\u00e9d\u00e9ration internationale de surf (ISA) a exprim\u00e9 le m\u00e9pris mondial face \u00e0 la perspective de d\u00e9truire ce r\u00e9cif pour une nouvelle tour. Ils ont soumis une proposition alternative pour le jugement \u00e0 Teahupo\u2019o en 2024, en utilisant le cadre en bois d&rsquo;origine.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cependant, malheureusement, en d\u00e9cembre 2024, le pr\u00e9sident de Paris 2024, Tony Estanguet, a fait la d\u00e9claration suivante (selon Reuters): <\/span><\/p>\n<p><em><span style=\"font-weight: 400;\">\u00ab\u00a0C&rsquo;est une option qui avait \u00e9t\u00e9 envisag\u00e9e mais rejet\u00e9e car cela signifierait que les \u00e9v\u00e9nements seraient jug\u00e9s \u00e0 une distance de 900 m\u00e8tres.\u00a0\u00bb. <\/span><\/em><\/p>\n<p><span style=\"font-weight: 400;\">Cela malgr\u00e9 le fait que la tour en bois actuellement utilis\u00e9e soit acceptable pour les \u00e9v\u00e9nements de la World Surf League (WSL) comme le Tahiti Pro, o\u00f9 elle est d\u00e9mont\u00e9e et r\u00e9assembl\u00e9e pour chaque \u00e9v\u00e9nement afin de minimiser l&rsquo;impact. Cela a \u00e9t\u00e9 un r\u00e9veil brutal pour la communaut\u00e9 du surf, confirmant les soup\u00e7ons selon lesquels m\u00eame dans un monde avec des drones 8K et une technologie de diffusion, un sport qui c\u00e9l\u00e8bre les forces naturelles semble causer leur destruction. \u00c0 chacun d&rsquo;en tirer ses propres conclusions.<\/span><\/p>\n<h4><span style=\"font-weight: 400;\">Est-ce l\u00e0 le futur du surf comp\u00e9titif ?<\/span><\/h4>\n<p><span style=\"font-weight: 400;\">Le surf comp\u00e9titif est connu pour \u00eatre frustrant, avec des annulations d&rsquo;\u00e9v\u00e9nements et des changements de lieu fr\u00e9quents \u00e9tant le r\u00e9sultat de tentatives de cr\u00e9er une uniformit\u00e9 dans un sport qui d\u00e9pend du caprice de Dame Nature. Les zones o\u00f9 se d\u00e9roule le surf comp\u00e9titif abritent les meilleures vagues de la plan\u00e8te, pensez \u00e0 Margaret River, en Australie, ou \u00e0 Pipeline, \u00e0 O&rsquo;ahu. Ces sites sont souvent des lieux d&rsquo;une grande valeur environnementale ainsi que de vagues \u00e9voluants.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cependant, la r\u00e9gion locale est souvent surcharg\u00e9e par l&rsquo;infrastructure touristique et un afflux massif mais temporaire de personnes qui exercent une pression excessive sur la communaut\u00e9 et l&rsquo;environnement local, des sites qui ne sont pas toujours \u00e9quip\u00e9s pour cela. Non seulement ils sont souvent fragiles, mais beaucoup de ces sites sont \u00e9galement plus vuln\u00e9rables aux impacts futurs du changement climatique. Par exemple, Pipeline, une escale fr\u00e9quente du circuit de la World Surf League (WSL), est extr\u00eamement expos\u00e9e aux inondations, aux temp\u00eates et \u00e0 l&rsquo;\u00e9l\u00e9vation du niveau de la mer. Bien que la WSL soit l&rsquo;une des principales organisations sportives \u00e0 int\u00e9grer des pratiques durables dans ses \u00e9v\u00e9nements, passant au bilan carbone neutre en 2019 et travaillant aux c\u00f4t\u00e9s des communaut\u00e9s autochtones et des Premi\u00e8res Nations, il semble de plus en plus difficile de justifier les co\u00fbts et les pertes (\u00e9v\u00e9nements report\u00e9s) de ces \u00e9v\u00e9nements.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Bien qu&rsquo;ils ne soient pas parfaits en raison de leurs besoins \u00e9nerg\u00e9tiques (qui sont de plus en plus fournis par des \u00e9nergies vertes telles que l&rsquo;\u00e9nergie solaire et hydro\u00e9lectrique), les piscines \u00e0 vagues semblent \u00eatre une \u00e9tape logique dans la progression et l&rsquo;\u00e9volution du surf comp\u00e9titif. La technologie pourrait \u00e9galement \u00eatre consid\u00e9r\u00e9e comme un moyen d&rsquo;am\u00e9liorer la pr\u00e9cision du jugement de ces \u00e9v\u00e9nements, sans variations naturelles dans les vagues pour avantages. Les piscines \u00e0 vagues peuvent \u00eatre construites dans des r\u00e9gions \u00e9quip\u00e9es pour faire face \u00e0 l&rsquo;afflux de stress environnemental qu&rsquo;entra\u00eene l&rsquo;organisation d&rsquo;un \u00e9v\u00e9nement, en particulier un \u00e9v\u00e9nement de la taille des Jeux olympiques, comme \u00e0 URBN SURF \u00e0 Melbourne.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2311 size-full\" src=\"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/Alaiabay_sunrise.-jpg-1024x683-1-1.jpg\" alt=\"The modification of wave pool settings is rapidly progressing, \" width=\"1024\" height=\"683\" srcset=\"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/Alaiabay_sunrise.-jpg-1024x683-1-1.jpg 1024w, https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/Alaiabay_sunrise.-jpg-1024x683-1-1-300x200.jpg 300w, https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/Alaiabay_sunrise.-jpg-1024x683-1-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Translation\" aria-label=\"Translated text\" data-ved=\"2ahUKEwjSta2a7ZGFAxXY_7sIHarkDEoQ3ewLegQIFBAU\"><span class=\"Y2IQFc\" lang=\"fr\">Pour beaucoup, cela pourrait \u00eatre une pens\u00e9e inconfortable. Apr\u00e8s tout, l\u2019essence du surf est d\u2019appr\u00e9cier le monde naturel en exploitant sa puissance brute pour danser sur des vagues cr\u00e9\u00e9es \u00e0 partir d\u2019\u00e9nergie parcourant des milliers de kilom\u00e8tres pour vous atteindre. Cependant, le surf de comp\u00e9tition, c&rsquo;est le surf en tant que sport, qui doit \u00eatre jug\u00e9 et \u00e9valu\u00e9 \u2013 et, en fin de compte, repousser les limites de ce qui est possible. La transition du surf de comp\u00e9tition vers un sport de piscine pourrait aider \u00e0 emp\u00eacher le surf de nuire \u00e0 la plan\u00e8te et de contribuer \u00e0 sa disparition. Les piscines \u00e0 vagues sont-elles donc la r\u00e9ponse pour maintenir le surf durable?<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le fait que le surf soit reconnu comme sport olympique est un tournant \u00e0 la fois doux et amer, un sentiment partag\u00e9 par de nombreux surfeurs.<\/p>\n","protected":false},"author":7,"featured_media":2308,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les mar\u00e9es noires du surf: les piscines \u00e0 vagues sont-elles la solution? - Ala\u00efa Bay<\/title>\n<meta name=\"description\" content=\"Les piscines \u00e0 vagues sont-elles la r\u00e9ponse dont le surf comp\u00e9titif a besoin?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les mar\u00e9es noires du surf: les piscines \u00e0 vagues sont-elles la solution? - Ala\u00efa Bay\" \/>\n<meta property=\"og:description\" content=\"Les piscines \u00e0 vagues sont-elles la r\u00e9ponse dont le surf comp\u00e9titif a besoin?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/\" \/>\n<meta property=\"og:site_name\" content=\"Ala\u00efa Bay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/alaia.bay\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-02T07:32:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T17:40:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Coco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/les-piscines-a-vagues-sont-elles-la-solution\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/les-piscines-a-vagues-sont-elles-la-solution\\\/\"},\"author\":{\"name\":\"Coco\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#\\\/schema\\\/person\\\/94ab0e9461bc75b0e27786dd5d43158d\"},\"headline\":\"Les mar\u00e9es noires du surf: les piscines \u00e0 vagues sont-elles la solution?\",\"datePublished\":\"2024-04-02T07:32:39+00:00\",\"dateModified\":\"2026-03-17T17:40:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/les-piscines-a-vagues-sont-elles-la-solution\\\/\"},\"wordCount\":1151,\"publisher\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/les-piscines-a-vagues-sont-elles-la-solution\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1.webp\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/les-piscines-a-vagues-sont-elles-la-solution\\\/\",\"url\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/les-piscines-a-vagues-sont-elles-la-solution\\\/\",\"name\":\"Les mar\u00e9es noires du surf: les piscines \u00e0 vagues sont-elles la solution? - Ala\u00efa Bay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/les-piscines-a-vagues-sont-elles-la-solution\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/les-piscines-a-vagues-sont-elles-la-solution\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1.webp\",\"datePublished\":\"2024-04-02T07:32:39+00:00\",\"dateModified\":\"2026-03-17T17:40:37+00:00\",\"description\":\"Les piscines \u00e0 vagues sont-elles la r\u00e9ponse dont le surf comp\u00e9titif a besoin?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/les-piscines-a-vagues-sont-elles-la-solution\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alaia.ch\\\/bay\\\/les-piscines-a-vagues-sont-elles-la-solution\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/les-piscines-a-vagues-sont-elles-la-solution\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1.webp\",\"contentUrl\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1.webp\",\"width\":1536,\"height\":1024,\"caption\":\"Coraux \u00e0 Tahiti. Photo : Tahiti Tourisme (Gregory Lecoeur)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/les-piscines-a-vagues-sont-elles-la-solution\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les mar\u00e9es noires du surf: les piscines \u00e0 vagues sont-elles la solution?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#website\",\"url\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/\",\"name\":\"Ala\u00efa Bay\",\"description\":\"Surf the Swiss Alps!\",\"publisher\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#organization\",\"name\":\"Ala\u00efa Bay\",\"url\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-alaia-bay.png\",\"contentUrl\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo-alaia-bay.png\",\"width\":160,\"height\":160,\"caption\":\"Ala\u00efa Bay\"},\"image\":{\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/alaia.bay\\\/\",\"https:\\\/\\\/www.instagram.com\\\/alaia.bay\\\/?hl=en\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/AlaaActionSports\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/alaa-sa\",\"https:\\\/\\\/www.tiktok.com\\\/@alaia.actionsports\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alaia.ch\\\/bay\\\/#\\\/schema\\\/person\\\/94ab0e9461bc75b0e27786dd5d43158d\",\"name\":\"Coco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77ecac894c0f195b8f1adf2e9ab42f3dd50a0f54cf6c466f96526171435775bf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77ecac894c0f195b8f1adf2e9ab42f3dd50a0f54cf6c466f96526171435775bf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77ecac894c0f195b8f1adf2e9ab42f3dd50a0f54cf6c466f96526171435775bf?s=96&d=mm&r=g\",\"caption\":\"Coco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les mar\u00e9es noires du surf: les piscines \u00e0 vagues sont-elles la solution? - Ala\u00efa Bay","description":"Les piscines \u00e0 vagues sont-elles la r\u00e9ponse dont le surf comp\u00e9titif a besoin?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/","og_locale":"fr_FR","og_type":"article","og_title":"Les mar\u00e9es noires du surf: les piscines \u00e0 vagues sont-elles la solution? - Ala\u00efa Bay","og_description":"Les piscines \u00e0 vagues sont-elles la r\u00e9ponse dont le surf comp\u00e9titif a besoin?","og_url":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/","og_site_name":"Ala\u00efa Bay","article_publisher":"https:\/\/www.facebook.com\/alaia.bay\/","article_published_time":"2024-04-02T07:32:39+00:00","article_modified_time":"2026-03-17T17:40:37+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1.webp","type":"image\/webp"}],"author":"Coco","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Coco","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/#article","isPartOf":{"@id":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/"},"author":{"name":"Coco","@id":"https:\/\/alaia.ch\/bay\/#\/schema\/person\/94ab0e9461bc75b0e27786dd5d43158d"},"headline":"Les mar\u00e9es noires du surf: les piscines \u00e0 vagues sont-elles la solution?","datePublished":"2024-04-02T07:32:39+00:00","dateModified":"2026-03-17T17:40:37+00:00","mainEntityOfPage":{"@id":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/"},"wordCount":1151,"publisher":{"@id":"https:\/\/alaia.ch\/bay\/#organization"},"image":{"@id":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/#primaryimage"},"thumbnailUrl":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1.webp","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/","url":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/","name":"Les mar\u00e9es noires du surf: les piscines \u00e0 vagues sont-elles la solution? - Ala\u00efa Bay","isPartOf":{"@id":"https:\/\/alaia.ch\/bay\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/#primaryimage"},"image":{"@id":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/#primaryimage"},"thumbnailUrl":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1.webp","datePublished":"2024-04-02T07:32:39+00:00","dateModified":"2026-03-17T17:40:37+00:00","description":"Les piscines \u00e0 vagues sont-elles la r\u00e9ponse dont le surf comp\u00e9titif a besoin?","breadcrumb":{"@id":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/#primaryimage","url":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1.webp","contentUrl":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/03\/le-corail-a-tahiti-et-ses-iles-a-gregory-lecoeur-1536x1024-1.webp","width":1536,"height":1024,"caption":"Coraux \u00e0 Tahiti. Photo : Tahiti Tourisme (Gregory Lecoeur)"},{"@type":"BreadcrumbList","@id":"https:\/\/alaia.ch\/bay\/les-piscines-a-vagues-sont-elles-la-solution\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alaia.ch\/bay\/"},{"@type":"ListItem","position":2,"name":"Les mar\u00e9es noires du surf: les piscines \u00e0 vagues sont-elles la solution?"}]},{"@type":"WebSite","@id":"https:\/\/alaia.ch\/bay\/#website","url":"https:\/\/alaia.ch\/bay\/","name":"Ala\u00efa Bay","description":"Surf the Swiss Alps!","publisher":{"@id":"https:\/\/alaia.ch\/bay\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alaia.ch\/bay\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/alaia.ch\/bay\/#organization","name":"Ala\u00efa Bay","url":"https:\/\/alaia.ch\/bay\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/alaia.ch\/bay\/#\/schema\/logo\/image\/","url":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/05\/logo-alaia-bay.png","contentUrl":"https:\/\/alaia.ch\/bay\/wp-content\/uploads\/2024\/05\/logo-alaia-bay.png","width":160,"height":160,"caption":"Ala\u00efa Bay"},"image":{"@id":"https:\/\/alaia.ch\/bay\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alaia.bay\/","https:\/\/www.instagram.com\/alaia.bay\/?hl=en","https:\/\/www.youtube.com\/c\/AlaaActionSports\/","https:\/\/www.linkedin.com\/company\/alaa-sa","https:\/\/www.tiktok.com\/@alaia.actionsports"]},{"@type":"Person","@id":"https:\/\/alaia.ch\/bay\/#\/schema\/person\/94ab0e9461bc75b0e27786dd5d43158d","name":"Coco","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/77ecac894c0f195b8f1adf2e9ab42f3dd50a0f54cf6c466f96526171435775bf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/77ecac894c0f195b8f1adf2e9ab42f3dd50a0f54cf6c466f96526171435775bf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/77ecac894c0f195b8f1adf2e9ab42f3dd50a0f54cf6c466f96526171435775bf?s=96&d=mm&r=g","caption":"Coco"}}]}},"_links":{"self":[{"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/posts\/2362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/comments?post=2362"}],"version-history":[{"count":3,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/posts\/2362\/revisions"}],"predecessor-version":[{"id":5551,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/posts\/2362\/revisions\/5551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/media\/2308"}],"wp:attachment":[{"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/media?parent=2362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/categories?post=2362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alaia.ch\/bay\/wp-json\/wp\/v2\/tags?post=2362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}